{"id":60,"date":"2024-08-17T13:38:41","date_gmt":"2024-08-17T13:38:41","guid":{"rendered":"http:\/\/nau-systems.com\/?page_id=60"},"modified":"2026-05-05T14:28:26","modified_gmt":"2026-05-05T14:28:26","slug":"unsere-projekte-2-2-2-2-2","status":"publish","type":"page","link":"https:\/\/nau-systems.com\/en\/","title":{"rendered":"Home"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"60\" class=\"elementor elementor-60\" data-elementor-post-type=\"page\">\n\t\t\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-7cfecb2 animated-fast e-flex e-con-boxed elementor-invisible e-con e-parent\" data-id=\"7cfecb2\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;video&quot;,&quot;background_video_link&quot;:&quot;https:\\\/\\\/nau-systems.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/about-us-1-block.mp4&quot;,&quot;background_play_on_mobile&quot;:&quot;yes&quot;,&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-background-video-container\">\n\t\t\t\t\t\t\t<video class=\"elementor-background-video-hosted elementor-html5-video\" autoplay muted playsinline loop><\/video>\n\t\t\t\t\t<\/div>\t\t<div class=\"elementor-element elementor-element-bbf9cb0 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"bbf9cb0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.23.0 - 05-08-2024 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h1 class=\"elementor-heading-title elementor-size-default\">Tailor-made solutions for your energy needs\n<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e578855 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"e578855\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.23.0 - 05-08-2024 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p class=\"p1\">Enjoy more independence and fun with environmentally friendly energy. NAU SYSTEMS offers you everything you need for portable batteries, camping equipment and EcoFlow photovoltaic systems for your home storage - for more savings and freedom.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8a5641f min-wid-but wid-3 elementor-mobile-align-justify elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-button\" data-id=\"8a5641f\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Get free advice<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e26ed8d elementor-absolute icon-main-screen elementor-widget elementor-widget-image\" data-id=\"e26ed8d\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/nau-systems.com\/wp-content\/uploads\/2024\/08\/Vector-4.svg\" class=\"attachment-large size-large wp-image-54\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-4e15d24 animated-fast e-flex e-con-boxed elementor-invisible e-con e-parent\" data-id=\"4e15d24\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9cb5751 elementor-widget__width-initial elementor-widget-tablet__width-initial elementor-widget-mobile__width-inherit block-icons-moving elementor-view-default elementor-position-top elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"9cb5751\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<link rel=\"stylesheet\" href=\"https:\/\/nau-systems.com\/wp-content\/plugins\/elementor\/assets\/css\/widget-icon-box.min.css\">\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon elementor-animation-\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"80\" height=\"80\" viewbox=\"0 0 80 80\" fill=\"none\"><path d=\"M40.4875 2.2509C40.5305 3.49821 40.6452 8.35843 40.7169 13.0466C40.8029 17.7348 40.9032 22.3226 40.9606 23.2258L41.0466 24.8746L42.9534 12.6452C44 5.90681 44.8746 0.372761 44.9176 0.344087C44.9462 0.315413 45.5197 0.358425 46.1792 0.473121C47.0824 0.602153 47.3835 0.702509 47.3548 0.860215C47.3118 1.2043 45.6488 11.914 44.5878 18.767C44.0287 22.2796 43.6129 25.1613 43.6416 25.19C43.6559 25.2186 45.4767 19.957 47.6703 13.5197C49.8638 7.0681 51.6703 1.77778 51.6846 1.76344C51.7419 1.67742 54.0502 2.50896 54.0502 2.62366C54.0502 2.7957 45.8925 26.6953 45.8065 26.7814C45.7634 26.8244 45.233 26.681 44.6165 26.4803C42.2939 25.6631 39.8136 25.4767 37.4624 25.9355C33.1039 26.7814 29.5341 29.3763 27.4409 33.2043C22.7384 41.8495 28.0287 52.5448 37.8065 54.1219C38.5376 54.2366 39.5842 54.3369 40.1434 54.3369C41.4767 54.3369 43.6703 53.8925 45.1613 53.319C51.5125 50.8817 55.3548 44.0287 54.0645 37.4194C53.9068 36.6308 53.8495 36.0287 53.9212 35.9713C53.9928 35.9283 54.681 35.7706 55.4552 35.6272C56.2151 35.4839 61.8208 34.3943 67.8853 33.19C74.8387 31.8136 78.9534 31.0538 79.0108 31.1398C79.1255 31.3118 79.4695 33.405 79.3979 33.4767C79.3548 33.5197 75.9713 34.2079 62.595 36.8459C58.5806 37.6344 55.2545 38.3226 55.2115 38.3656C55.1685 38.4229 56.3871 38.4229 57.9211 38.3656C59.4552 38.3226 64.3584 38.2079 68.8172 38.1362C73.276 38.0645 77.6057 37.9642 78.466 37.9211L80 37.8495V39.1254V40.4014L77.8208 40.4875C76.6165 40.5305 71.7563 40.6452 67.0251 40.7168C62.2939 40.8029 57.6774 40.9032 56.7742 40.9606L55.1254 41.0466L58.638 41.5914C60.5735 41.8925 66.0789 42.7527 70.8674 43.4982C75.6703 44.2437 79.6273 44.8745 79.6559 44.9176C79.6989 44.9462 79.6416 45.5197 79.5269 46.1792C79.3979 47.0824 79.2975 47.3835 79.1398 47.3548C78.5376 47.2688 63.2545 44.9032 59.3692 44.3011C56.8889 43.8996 54.8387 43.6129 54.81 43.6416C54.7814 43.6559 60.043 45.4767 66.4803 47.6703C72.9319 49.8638 78.2222 51.6703 78.2366 51.6846C78.3369 51.7419 77.4767 54.0502 77.3763 54.0502C77.3047 54.0502 72.043 52.2724 65.6774 50.1075C59.3262 47.9426 54.0645 46.1649 53.9785 46.1649C53.9068 46.1649 58.6237 48.7885 64.4445 51.9857C70.2796 55.1828 75.1971 57.8925 75.3692 58.0072L75.6846 58.2079L75.0968 59.2401C74.767 59.8136 74.4803 60.3154 74.466 60.3441C74.4229 60.3871 62.5376 53.8925 55.1398 49.7921C53.8065 49.0466 52.7025 48.4731 52.6882 48.4875C52.6595 48.5161 55.9713 51.2115 60.043 54.4803C64.1147 57.7491 68.4588 61.2617 69.7061 62.2652L71.9713 64.1004L71.1685 65.0896L70.3656 66.0932L66.4086 62.8961C64.2151 61.1326 59.957 57.7061 56.9462 55.2688C53.9211 52.8172 51.2975 50.724 51.1398 50.6093C50.7527 50.3369 50.724 50.3082 59.7706 60.6452C63.871 65.3333 67.2402 69.2186 67.2402 69.2616C67.2402 69.3047 66.8244 69.7061 66.3083 70.1505L65.3907 70.9677L57.405 61.8351C49.7348 53.0323 48.7599 51.9426 48.9319 52.2581C48.9749 52.3297 51.8853 57.1613 55.4122 62.9821C58.9247 68.8172 61.7921 73.5914 61.7634 73.6057C61.5054 73.8208 59.6129 74.8674 59.5842 74.8244C59.5556 74.7957 56.7025 70.0932 53.2617 64.3728C49.8065 58.6523 46.8961 53.8781 46.7814 53.7634C46.681 53.6487 46.7527 53.9642 46.9677 54.4803C47.9427 56.8889 55.5269 76.5161 55.5412 76.6738C55.5556 76.8459 53.8065 77.6774 53.3907 77.6918C53.3047 77.7061 51.2401 72.5591 48.8172 66.2796C46.3799 59.9857 44.3298 54.767 44.2581 54.6953C44.1721 54.6093 44.1577 54.6523 44.2151 54.8387C44.2581 54.9964 44.9032 58.2509 45.6631 62.0789C46.4229 65.9068 47.4839 71.2545 48.0143 73.9785C48.6452 77.1326 48.9462 78.9534 48.8602 79.0108C48.6882 79.1254 46.595 79.4695 46.5233 79.3979C46.4803 79.3548 46.1362 77.6201 43.2258 62.9534C42.3943 58.7384 41.6774 55.2545 41.6344 55.2115C41.5771 55.1685 41.5914 56.4158 41.6344 57.9928C41.6774 59.5699 41.7921 64.5018 41.8638 68.9606C41.9355 73.4194 42.0358 77.7204 42.0645 78.5233L42.1362 80H40.8746H39.5986L39.5125 77.7348C39.4695 76.5018 39.3548 71.6416 39.2832 66.9534C39.1971 62.2652 39.0968 57.6774 39.0394 56.7742L38.9534 55.1254L38.4086 58.638C38.1075 60.5735 37.2473 66.0789 36.5018 70.8817C35.7563 75.6703 35.1111 79.6272 35.0824 79.6559C35.0538 79.6989 34.4803 79.6416 33.8208 79.5412C32.7599 79.3692 32.6165 79.3118 32.6452 79.0681C32.6738 78.9104 33.5197 73.405 34.552 66.8244C35.5699 60.2437 36.3871 54.8387 36.3584 54.81C36.3441 54.7814 34.5233 60.043 32.3298 66.4803C30.1362 72.9319 28.3297 78.2222 28.3154 78.2366C28.2581 78.3226 25.9498 77.491 25.9498 77.3763C25.9498 77.3047 26.9821 74.2366 28.2294 70.5663C29.491 66.8817 31.2545 61.6774 32.172 58.9964C33.0896 56.3154 33.8351 54.0645 33.8351 53.9785C33.8351 53.9068 33.3907 54.638 32.8602 55.6272C30.3082 60.3011 22.1649 75.0968 21.9928 75.3692L21.7921 75.6846L20.7599 75.0968C20.1864 74.7814 19.6846 74.4946 19.6559 74.466C19.5986 74.4229 20.2294 73.2616 27.0538 60.8746C29.5197 56.3871 31.5269 52.7025 31.5125 52.6738C31.4839 52.6595 28.7885 55.9713 25.5197 60.043C22.2509 64.1147 18.7384 68.4588 17.7348 69.7061L15.8996 71.9713L14.9104 71.1685L13.9068 70.3656L17.1039 66.4086C18.8674 64.2151 22.2939 59.9713 24.7312 56.9462C27.1828 53.9211 29.276 51.3118 29.3907 51.1398C29.6631 50.7384 30.0072 50.4373 19.6559 59.4982C14.8387 63.7133 10.8387 67.1828 10.7814 67.2115C10.7097 67.2258 10.2939 66.8244 9.84946 66.3226L9.03226 65.3907L18.1649 57.405C23.1971 53.0179 27.4409 49.2903 27.5986 49.1326L27.8853 48.8459L27.5269 49.0609C27.3262 49.1756 22.4946 52.086 16.8029 55.5412C11.0968 58.9964 6.4086 61.7921 6.39427 61.7634C6.17921 61.5054 5.13261 59.6129 5.17562 59.5842C5.2043 59.5556 9.90681 56.7025 15.6272 53.2616C21.3477 49.8065 26.1219 46.8817 26.2366 46.767C26.4229 46.5806 26.4229 46.5806 26.1649 46.7097C25.6487 46.9677 3.51254 55.5125 3.31183 55.5412C3.12545 55.5556 2.17921 53.405 2.30824 53.2616C2.36559 53.2186 23.9283 44.8315 25.147 44.3871C25.7491 44.172 25.233 44.2007 23.9427 44.4588C9.87814 47.2832 1.06093 48.9749 0.989249 48.8602C0.874553 48.6738 0.51613 46.6093 0.587815 46.5376C0.645162 46.4803 3.69892 45.8638 17.405 43.1541C21.4194 42.3656 24.7455 41.6774 24.7885 41.6344C24.8315 41.5771 23.5556 41.5771 21.9355 41.6344C20.3154 41.6774 15.4552 41.7921 11.1111 41.8638C6.78136 41.9355 2.49462 42.0358 1.62007 42.0789L0 42.1362V40.8746V39.6129L2.05018 39.5269C3.16846 39.4695 8.24373 39.3548 13.3333 39.2688C18.4229 39.1828 23.0968 39.0681 23.7133 39.0108L24.8459 38.9247L21.276 38.3799C10.9677 36.8029 0.401435 35.1398 0.344087 35.0824C0.315414 35.0538 0.358419 34.4803 0.473114 33.8208C0.602147 32.9176 0.702509 32.6165 0.860215 32.6452C1.46237 32.7312 16.7455 35.0968 20.6308 35.6989C23.1111 36.1004 25.1613 36.3871 25.19 36.3584C25.2186 36.3441 19.957 34.5233 13.5197 32.3297C7.0681 30.1362 1.77777 28.3297 1.76344 28.3154C1.67742 28.2581 2.50896 25.9498 2.62365 25.9498C2.69534 25.9498 7.95699 27.7276 14.3082 29.8925C20.6738 32.0573 25.9498 33.8351 26.0215 33.8351C26.1075 33.8208 25.9785 33.7204 25.7348 33.5914C24.6738 33.0323 4.91756 22.1649 4.63082 21.9928L4.31541 21.7921L4.90322 20.7599C5.23297 20.1864 5.51971 19.6846 5.53405 19.6559C5.57706 19.6129 17.4624 26.1075 24.8602 30.2079C26.1936 30.9534 27.2975 31.5269 27.3118 31.5125C27.3405 31.4839 24.0287 28.7885 19.957 25.5197C15.8853 22.2509 11.5412 18.7384 10.2939 17.7348L8.02868 15.8996L8.83154 14.9104L9.63441 13.9211L14.7384 18.0215C26.7097 27.6559 28.7599 29.2903 28.9606 29.448C29.2473 29.6631 28.8315 29.1756 20.2294 19.3548C16.129 14.6667 12.7599 10.7814 12.7599 10.7384C12.7599 10.6953 13.1756 10.2939 13.6774 9.84947L14.6093 9.03226L22.595 18.1649C30.2652 26.9534 31.2401 28.0573 31.0681 27.7419C31.0251 27.6559 29.0466 24.3728 26.6523 20.4301C19.1541 8.01434 18.1935 6.42294 18.2366 6.37993C18.4946 6.17922 20.3871 5.13262 20.4158 5.17563C20.4444 5.2043 23.2975 9.90682 26.7384 15.6272C30.1936 21.3477 33.1039 26.1219 33.2186 26.2366C33.3477 26.3799 33.3333 26.2366 33.147 25.8064C33.0036 25.448 31.957 22.81 30.8531 19.9283C29.7348 17.0466 27.828 12.1147 26.6093 8.96058C25.3763 5.80646 24.4301 3.1828 24.4875 3.13979C24.6595 2.98208 26.6667 2.2509 26.724 2.30824C26.7814 2.35126 35.1111 23.7849 35.6129 25.147C35.6559 25.2903 35.7276 25.3907 35.7563 25.362C35.7849 25.3333 34.724 19.8566 33.405 13.19C31.8996 5.62007 31.0538 1.0466 31.1398 0.989248C31.3405 0.860216 33.3907 0.51613 33.4767 0.587814C33.5054 0.630825 34.595 6.06452 35.8996 12.6738C37.2043 19.2975 38.3226 24.7455 38.3656 24.7885C38.4086 24.8315 38.4229 23.6129 38.3656 22.0789C38.3226 20.5448 38.2079 15.6416 38.1362 11.1828C38.0645 6.72401 37.9642 2.39426 37.9212 1.53405L37.8495 -2.91614e-07H39.1255H40.4014L40.4875 2.2509Z\" fill=\"#FFB336\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tSustainable energy\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tPower your home with emission-free, renewable energy directly from the sun.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7208f16 elementor-widget__width-initial elementor-widget-tablet__width-initial elementor-widget-mobile__width-inherit block-icons-moving elementor-view-default elementor-position-top elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"7208f16\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon elementor-animation-\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"77\" height=\"80\" viewbox=\"0 0 77 80\" fill=\"none\"><path d=\"M66.9942 13.6225C66.1426 14.5349 62.787 18.0527 59.5227 21.4184C56.2685 24.7943 53.0954 28.1093 52.4972 28.7886L51.3922 30.0152L61.388 22.7161C66.8928 18.6914 71.4244 15.3966 71.4751 15.4068C71.5156 15.4068 71.8907 15.8427 72.2759 16.3901C72.8234 17.12 72.9653 17.4039 72.8335 17.4951C72.5598 17.708 63.8109 24.1049 58.2149 28.2006C55.3358 30.2889 53.0041 32.0326 53.0041 32.0732C52.994 32.1036 58.002 29.6705 64.1049 26.6698C70.218 23.6589 75.2362 21.1954 75.2564 21.1954C75.3578 21.1751 76.402 23.3953 76.3209 23.4764C76.1992 23.598 53.5313 34.7293 53.4096 34.7293C53.3488 34.7293 53.0751 34.2528 52.7811 33.6749C51.7166 31.4548 50.0946 29.5692 48.1076 28.231C44.4276 25.7472 40.0684 25.0579 35.8815 26.2845C26.4433 29.0724 22.6213 40.376 28.4201 48.4051C28.856 49.0032 29.5251 49.8142 29.9205 50.2096C30.8633 51.1524 32.7287 52.3892 34.1885 53.038C40.4029 55.8056 47.9657 53.6767 51.7268 48.0908C52.1728 47.4217 52.5581 46.9554 52.6493 46.9655C52.7304 46.9858 53.3285 47.3609 53.9773 47.8069C54.616 48.2429 59.3503 51.4363 64.4902 54.8729C70.3802 58.8165 73.827 61.1888 73.8067 61.2901C73.7662 61.4929 72.5294 63.2163 72.428 63.2163C72.3672 63.2163 69.4881 61.3104 58.1642 53.7172C54.7681 51.4362 51.9295 49.5709 51.8687 49.5709C51.7977 49.5811 52.6594 50.4428 53.7847 51.4869C54.8999 52.5413 58.4481 55.9273 61.6516 59.0294C64.8551 62.1316 67.9877 65.1222 68.6264 65.7001L69.7618 66.7341L67.9573 68.5386L66.3555 67.0585C65.4735 66.2374 61.9557 62.8818 58.5596 59.587C55.1533 56.3024 51.818 53.109 51.1388 52.5109L49.9121 51.4058L52.0106 54.2748C53.1663 55.8563 56.4509 60.3575 59.3098 64.2706C62.1788 68.1939 64.5307 71.438 64.5206 71.4887C64.5307 71.5394 64.0847 71.9043 63.5372 72.2896C62.8073 72.837 62.5234 72.9789 62.4322 72.8471C62.0673 72.3605 52.9332 59.881 50.6116 56.7079C49.1416 54.6702 47.8947 53.0177 47.8542 53.0177C47.8237 53.0076 50.2568 58.0157 53.2576 64.1186C56.2685 70.2316 58.7319 75.2498 58.7319 75.2701C58.7624 75.3816 56.5219 76.4055 56.4509 76.3345C56.4003 76.2838 53.9368 71.3062 50.9664 65.2743C48.0062 59.2524 45.5427 54.2748 45.4819 54.214C45.4312 54.1633 46.9113 59.3538 48.7666 65.7305C50.6319 72.1172 52.1931 77.5105 52.2337 77.7133L52.3148 78.0782L51.1692 78.3925C50.5305 78.5648 49.9729 78.7169 49.9425 78.727C49.8817 78.727 46.0699 65.7305 43.7382 57.6C43.3226 56.13 42.9475 54.9439 42.9272 54.9439C42.8867 54.9439 43.3226 59.1916 43.8903 64.3821C44.458 69.5727 45.046 75.1281 45.2183 76.7198L45.5225 79.6191L44.2553 79.7509L42.9779 79.8929L42.4406 74.8341C42.1365 72.0361 41.5485 66.6023 41.143 62.75C40.7375 58.8773 40.3624 55.542 40.332 55.3494C40.2508 54.8831 40.2509 54.8425 39.3385 68.5488C38.9228 74.7632 38.5579 79.8929 38.5274 79.9233C38.497 79.9537 37.9192 79.9436 37.24 79.8929L36.0133 79.8219L36.8243 67.7175C37.6252 56.0692 37.7063 54.6094 37.6049 54.954C37.5846 55.0352 36.2262 60.5095 34.6041 67.1193C32.9618 73.7291 31.6135 79.1325 31.5831 79.1224C31.2486 79.092 29.1703 78.4939 29.1805 78.4432C29.1805 78.4026 30.4882 73.06 32.1001 66.582C33.7019 60.0939 35.0198 54.6601 35.0198 54.4978C35.0299 54.3458 34.8576 54.6195 34.6447 55.1365C33.6309 57.529 25.1152 76.7704 25.0138 76.8921C24.9023 77.0239 23.0775 76.3751 22.7734 76.0912C22.7024 76.0405 24.8821 70.9412 27.6091 64.7876C30.3361 58.6138 32.5766 53.4739 32.5766 53.3726C32.5766 53.2509 32.536 53.2712 32.4448 53.4435C32.3637 53.5855 30.5186 56.3429 28.3492 59.587C26.1797 62.8311 23.1485 67.3626 21.5974 69.6639C19.8132 72.3403 18.7386 73.8406 18.6372 73.8204C18.4345 73.7798 16.711 72.543 16.711 72.4416C16.711 72.3808 17.6944 70.9108 26.0073 58.482C28.3998 54.9135 30.3564 51.9431 30.3564 51.8823C30.3463 51.8114 29.4744 52.7035 28.3897 53.849C27.305 54.9946 23.8987 58.5631 20.7965 61.7666C17.6944 64.9701 14.724 68.0824 14.1766 68.6704L13.1831 69.7653L11.3887 67.9709L12.9297 66.3083C13.7711 65.4061 17.1267 61.8883 20.391 58.5225C23.6452 55.1467 26.8184 51.8316 27.4165 51.1524L28.5215 49.9257L25.6525 52.0242C24.071 53.1799 19.5699 56.4646 15.6466 59.3335C11.7334 62.1924 8.4792 64.5342 8.43865 64.5342C8.38796 64.5443 8.023 64.0983 7.62763 63.561C6.99909 62.6891 6.93826 62.5472 7.13088 62.3951C7.26267 62.3039 11.7537 59.0091 17.1368 55.0858C22.5098 51.1524 26.9096 47.9083 26.9096 47.8678C26.9197 47.8374 21.9117 50.2704 15.8088 53.2712C9.69573 56.2821 4.67755 58.7456 4.65727 58.7456C4.5559 58.7658 3.51171 56.5457 3.59281 56.4646C3.6435 56.4139 6.54289 54.9743 10.0201 53.261C13.5177 51.5478 18.4446 49.1147 20.9892 47.8678C23.5337 46.6208 25.6525 45.5564 25.7133 45.4955C25.764 45.4449 24.9327 45.6476 23.8581 45.972C18.7487 47.4724 2.52835 52.1763 2.21408 52.2473L1.84913 52.3284L1.53485 51.1828C1.35237 50.5543 1.20031 49.9967 1.20031 49.9561C1.19017 49.8852 2.45739 49.5101 16.0419 45.5766C20.9587 44.1472 24.9834 42.9611 24.9936 42.9307C24.9834 42.9003 20.7357 43.3362 15.5452 43.9039C10.3547 44.4716 4.7992 45.0596 3.20758 45.232L0.308187 45.5361L0.1764 44.2689L0.0344669 42.9915L5.0932 42.4542C7.89121 42.1501 13.3149 41.5722 17.1774 41.1566C21.05 40.7511 24.3752 40.3861 24.5779 40.3456C25.0544 40.2543 25.5106 40.2847 11.7841 39.3724C5.39733 38.9466 0.115571 38.5715 0.0547446 38.5512C-0.0060818 38.5106 -0.0162208 37.9328 0.0243301 37.2637L0.105435 36.0269L12.2099 36.8379C18.8704 37.2941 24.507 37.6591 24.73 37.6591H25.1355L24.73 37.5577C24.507 37.4969 19.0326 36.1384 12.5647 34.5569C6.08669 32.9653 0.794797 31.6271 0.804935 31.5967C0.835348 31.2622 1.43347 29.1839 1.48416 29.1941C1.52471 29.1941 6.8673 30.5018 13.3453 32.1137C19.8335 33.7155 25.2774 35.0233 25.4396 35.0233C25.7032 35.0233 25.7032 35.0233 25.4295 34.932C24.882 34.7495 3.1873 25.139 3.0251 25.0173C2.88317 24.8957 3.73474 22.7059 3.92736 22.6958C3.99832 22.7059 25.176 32.0225 26.352 32.5699C26.9299 32.8437 26.5446 32.499 25.4498 31.7691C13.5075 23.8211 6.07656 18.7826 6.10697 18.6508C6.15766 18.4379 7.36405 16.7247 7.46543 16.7247C7.54653 16.7247 10.1418 18.4481 21.7495 26.2237C25.1456 28.5047 27.9842 30.37 28.045 30.37C28.116 30.3599 27.2137 29.4577 26.0276 28.3526C24.8516 27.2375 21.3338 23.8819 18.2114 20.8609C15.0991 17.8499 11.997 14.8897 11.3482 14.3017L10.1621 13.1967L11.9463 11.4125L13.4568 12.8014C14.2881 13.5515 17.958 17.0592 21.6177 20.5973C25.2774 24.1353 28.6634 27.3591 29.1399 27.7545L30.0016 28.4946L27.8625 25.585C21.6887 17.1809 15.3931 8.53338 15.3931 8.45227C15.3931 8.41172 15.8291 8.03662 16.3765 7.65139C17.1064 7.10395 17.3903 6.96202 17.4815 7.09381C17.8465 7.58043 26.9806 20.06 29.3021 23.2331C30.7721 25.2708 32.019 26.9232 32.0596 26.9232C32.09 26.9334 29.6569 21.9253 26.6562 15.8224C23.6452 9.70935 21.1818 4.69117 21.1818 4.67089C21.1615 4.56952 23.3817 3.52533 23.4628 3.60643C23.5135 3.65712 25.9769 8.63474 28.9371 14.6566C31.9075 20.6885 34.3811 25.6763 34.4318 25.727C34.5028 25.7777 34.4825 25.6154 34.4014 25.3519C34.0466 24.2063 27.7612 2.55211 27.6801 2.2277L27.599 1.86275L28.7445 1.54848C29.3832 1.37614 29.9408 1.22407 29.9712 1.21394C30.032 1.21394 33.8438 14.2105 36.1755 22.341C36.5911 23.8109 36.9662 24.9971 36.9865 24.9971C37.0271 24.9971 36.5911 20.7493 36.0234 15.5588C35.4557 10.3683 34.8677 4.81283 34.6954 3.22121L34.3912 0.321813L36.9257 0.0582302L37.6353 6.56666C39.2878 21.8442 39.5818 24.4496 39.6122 24.7031C39.6629 25.0579 39.7136 24.4192 40.5753 11.3922C40.9909 5.17779 41.3559 0.0480981 41.3863 0.0176849C41.4167 -0.0127283 41.9945 -0.00259443 42.6636 0.0379565L43.9004 0.119053L43.0894 12.2235C42.2987 23.8616 42.2074 25.3316 42.3088 24.9869C42.3392 24.8957 43.2618 21.1751 44.3566 16.6942C47.8339 2.61294 48.2799 0.808427 48.3408 0.808427C48.6652 0.848977 50.7434 1.4471 50.7333 1.49779C50.7333 1.53834 49.4255 6.88093 47.8136 13.3589C46.2118 19.8471 44.8939 25.2809 44.8939 25.4431C44.8838 25.6357 44.975 25.5242 45.1474 25.0883C45.2994 24.7335 46.4247 22.1281 47.6818 19.3098C48.9287 16.4814 51.0678 11.6457 52.4364 8.55365C53.7949 5.45151 54.981 2.92721 55.0519 2.93735C55.2851 2.94748 57.2214 3.84974 57.2214 3.93084C57.2316 4.00181 47.9657 25.0477 47.3574 26.3656C47.2864 26.4974 47.2662 26.6191 47.3067 26.6191C47.3473 26.6191 50.4697 21.9963 54.2511 16.3496C58.5393 9.93238 61.1751 6.10032 61.2765 6.12059C61.5097 6.17128 63.2027 7.37767 63.2128 7.48919C63.2027 7.53988 60.1309 12.1525 56.38 17.7486C52.6189 23.3547 49.5573 27.9978 49.5573 28.0586C49.5573 28.1195 50.4291 27.2679 51.4733 26.1426C52.5276 25.0275 55.9137 21.4793 59.0158 18.2757C62.1179 15.0722 65.1086 11.9397 65.6864 11.301L66.7205 10.1655L68.525 11.9701L66.9942 13.6225Z\" fill=\"#FFB336\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tTax incentives\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tYou may be eligible for federal, state and local tax incentives that can reduce your installation costs.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-24d4025 elementor-widget__width-initial elementor-widget-tablet__width-initial elementor-widget-mobile__width-inherit block-icons-moving elementor-view-default elementor-position-top elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"24d4025\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon elementor-animation-\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"81\" height=\"80\" viewbox=\"0 0 81 80\" fill=\"none\"><path d=\"M78.7059 40.4875C77.4586 40.5305 72.5984 40.6452 67.9102 40.7169C63.222 40.8029 58.6342 40.9032 57.731 40.9606L56.0822 41.0466L68.3116 42.9534C75.05 44 80.584 44.8746 80.6127 44.9176C80.6414 44.9462 80.5984 45.5197 80.4837 46.1792C80.3546 47.0824 80.2543 47.3835 80.0966 47.3548C79.7525 47.3118 69.0428 45.6488 62.1898 44.5878C58.6772 44.0287 55.7955 43.6129 55.7668 43.6416C55.7382 43.6559 60.9998 45.4767 67.4371 47.6703C73.8887 49.8638 79.179 51.6703 79.1933 51.6846C79.2794 51.7419 78.4478 54.0502 78.3331 54.0502C78.1611 54.0502 54.2614 45.8925 54.1754 45.8065C54.1324 45.7634 54.2758 45.233 54.4765 44.6165C55.2937 42.2939 55.4801 39.8136 55.0213 37.4624C54.1754 33.1039 51.5804 29.5341 47.7525 27.4409C39.1073 22.7384 28.412 28.0287 26.8349 37.8065C26.7202 38.5376 26.6199 39.5842 26.6199 40.1434C26.6199 41.4767 27.0643 43.6703 27.6378 45.1613C30.0751 51.5125 36.9281 55.3548 43.5374 54.0645C44.326 53.9068 44.9281 53.8495 44.9855 53.9212C45.0285 53.9928 45.1862 54.681 45.3295 55.4552C45.4729 56.2151 46.5625 61.8208 47.7668 67.8853C49.1432 74.8387 49.903 78.9534 49.817 79.0108C49.645 79.1255 47.5518 79.4695 47.4801 79.3979C47.4371 79.3548 46.7489 75.9713 44.1109 62.595C43.3224 58.5806 42.6342 55.2545 42.5912 55.2115C42.5338 55.1685 42.5338 56.3871 42.5912 57.9211C42.6342 59.4552 42.7489 64.3584 42.8206 68.8172C42.8923 73.276 42.9926 77.6057 43.0356 78.466L43.1073 80L41.8313 80L40.5554 80L40.4693 77.8208C40.4263 76.6165 40.3116 71.7563 40.2399 67.0251C40.1539 62.2939 40.0536 57.6774 39.9962 56.7742L39.9102 55.1254L39.3654 58.638C39.0643 60.5735 38.2041 66.0789 37.4586 70.8674C36.7131 75.6703 36.0822 79.6273 36.0392 79.6559C36.0106 79.6989 35.4371 79.6416 34.7776 79.5269C33.8744 79.3979 33.5733 79.2975 33.6019 79.1398C33.688 78.5376 36.0536 63.2545 36.6557 59.3692C37.0571 56.8889 37.3439 54.8387 37.3152 54.81C37.3009 54.7814 35.4801 60.043 33.2865 66.4803C31.093 72.9319 29.2865 78.2222 29.2722 78.2366C29.2149 78.3369 26.9066 77.4767 26.9066 77.3763C26.9066 77.3047 28.6844 72.043 30.8493 65.6774C33.0141 59.3262 34.7919 54.0645 34.7919 53.9785C34.7919 53.9068 32.1683 58.6237 28.9711 64.4445C25.774 70.2796 23.0643 75.1971 22.9496 75.3692L22.7489 75.6846L21.7166 75.0968C21.1432 74.767 20.6414 74.4803 20.6127 74.466C20.5697 74.4229 27.0643 62.5376 31.1647 55.1398C31.9102 53.8065 32.4837 52.7025 32.4693 52.6882C32.4407 52.6595 29.7453 55.9713 26.4765 60.043C23.2077 64.1147 19.6951 68.4588 18.6916 69.7061L16.8564 71.9713L15.8672 71.1685L14.8636 70.3656L18.0607 66.4086C19.8242 64.2151 23.2507 59.957 25.688 56.9462C28.1396 53.9211 30.2328 51.2975 30.3475 51.1398C30.6199 50.7527 30.6485 50.724 20.3116 59.7706C15.6235 63.871 11.7381 67.2402 11.6951 67.2402C11.6521 67.2402 11.2507 66.8244 10.8063 66.3083L9.98905 65.3907L19.1217 57.405C27.9245 49.7348 29.0141 48.7599 28.6987 48.9319C28.627 48.9749 23.7955 51.8853 17.9747 55.4122C12.1396 58.9247 7.36539 61.7921 7.35105 61.7634C7.136 61.5054 6.08941 59.6129 6.13242 59.5842C6.16109 59.5556 10.8636 56.7025 16.584 53.2617C22.3045 49.8065 27.0787 46.8961 27.1933 46.7814C27.308 46.681 26.9926 46.7527 26.4765 46.9677C24.0679 47.9427 4.44066 55.5269 4.28295 55.5412C4.11091 55.5556 3.27937 53.8065 3.26503 53.3907C3.25069 53.3047 8.39765 51.2401 14.6772 48.8172C20.9711 46.3799 26.1898 44.3298 26.2614 44.2581C26.3475 44.1721 26.3045 44.1577 26.1181 44.2151C25.9604 44.2581 22.7059 44.9032 18.8779 45.6631C15.05 46.4229 9.70231 47.4839 6.97829 48.0143C3.82417 48.6452 2.00338 48.9462 1.94603 48.8602C1.83134 48.6882 1.48725 46.595 1.55894 46.5233C1.60195 46.4803 3.33671 46.1362 18.0034 43.2258C22.2184 42.3943 25.7023 41.6774 25.7453 41.6344C25.7883 41.5771 24.541 41.5914 22.964 41.6344C21.3869 41.6774 16.455 41.7921 11.9962 41.8638C7.53743 41.9355 3.23636 42.0358 2.43349 42.0645L0.956788 42.1362L0.956788 40.8746L0.956788 39.5986L3.22202 39.5125C4.455 39.4695 9.31521 39.3548 14.0034 39.2832C18.6916 39.1971 23.2794 39.0968 24.1826 39.0394L25.8313 38.9534L22.3188 38.4086C20.3833 38.1075 14.8779 37.2473 10.0751 36.5018C5.28654 35.7563 1.32955 35.1111 1.30087 35.0824C1.25786 35.0538 1.31521 34.4803 1.41557 33.8208C1.58761 32.7599 1.64496 32.6165 1.88869 32.6452C2.04639 32.6738 7.55177 33.5197 14.1324 34.552C20.7131 35.5699 26.1181 36.3871 26.1468 36.3584C26.1754 36.3441 20.9138 34.5233 14.4765 32.3298C8.02489 30.1362 2.73456 28.3297 2.72023 28.3154C2.63421 28.2581 3.46575 25.9498 3.58044 25.9498C3.65213 25.9498 6.72023 26.9821 10.3905 28.2294C14.0751 29.491 19.2794 31.2545 21.9604 32.172C24.6414 33.0896 26.8923 33.8351 26.9783 33.8351C27.05 33.8351 26.3188 33.3907 25.3295 32.8602C20.6557 30.3082 5.86001 22.1649 5.58761 21.9928L5.2722 21.7921L5.86001 20.7599C6.17542 20.1864 6.46216 19.6846 6.49084 19.6559C6.53385 19.5986 7.69514 20.2294 20.0822 27.0538C24.5697 29.5197 28.2543 31.5269 28.283 31.5125C28.2973 31.4839 24.9855 28.7885 20.9138 25.5197C16.8421 22.2509 12.498 18.7384 11.2507 17.7348L8.98546 15.8996L9.78833 14.9104L10.5912 13.9068L14.5482 17.1039C16.7417 18.8674 20.9855 22.2939 24.0106 24.7312C27.0356 27.1828 29.645 29.276 29.817 29.3907C30.2184 29.6631 30.5195 30.0072 21.4586 19.6559C17.2435 14.8387 13.774 10.8387 13.7453 10.7814C13.731 10.7097 14.1324 10.2939 14.6342 9.84946L15.5661 9.03226L23.5518 18.1649C27.9389 23.1971 31.6665 27.4409 31.8242 27.5986L32.1109 27.8853L31.8959 27.5269C31.7812 27.3262 28.8708 22.4946 25.4156 16.8029C21.9604 11.0968 19.1647 6.4086 19.1933 6.39427C19.4514 6.17921 21.3439 5.13261 21.3726 5.17562C21.4012 5.2043 24.2543 9.90681 27.6951 15.6272C31.1503 21.3477 34.0751 26.1219 34.1898 26.2366C34.3761 26.4229 34.3761 26.4229 34.2471 26.1649C33.989 25.6487 25.4442 3.51254 25.4156 3.31183C25.4012 3.12545 27.5518 2.17921 27.6951 2.30824C27.7381 2.36559 36.1252 23.9283 36.5697 25.147C36.7847 25.7491 36.7561 25.233 36.498 23.9427C33.6736 9.87814 31.9819 1.06093 32.0966 0.989248C32.283 0.874553 34.3475 0.51613 34.4192 0.587814C34.4765 0.645162 35.093 3.69892 37.8027 17.405C38.5912 21.4194 39.2794 24.7455 39.3224 24.7885C39.3797 24.8315 39.3797 23.5556 39.3224 21.9355C39.2794 20.3154 39.1647 15.4552 39.093 11.1111C39.0213 6.78136 38.9209 2.49462 38.8779 1.62007L38.8206 -4.51521e-07L40.0822 -4.66566e-07L41.3439 -4.81611e-07L41.4299 2.05018C41.4873 3.16846 41.602 8.24373 41.688 13.3333C41.774 18.4229 41.8887 23.0968 41.946 23.7133L42.0321 24.8459L42.5769 21.276C44.1539 10.9677 45.817 0.401435 45.8743 0.344087C45.903 0.315413 46.4765 0.358418 47.136 0.473114C48.0392 0.602146 48.3403 0.702508 48.3116 0.860215C48.2256 1.46237 45.86 16.7455 45.2579 20.6308C44.8564 23.1111 44.5697 25.1613 44.5984 25.19C44.6127 25.2186 46.4335 19.957 48.627 13.5197C50.8206 7.0681 52.627 1.77777 52.6414 1.76344C52.6987 1.67741 55.007 2.50896 55.007 2.62365C55.007 2.69534 53.2292 7.95699 51.0643 14.3082C48.8994 20.6738 47.1217 25.9498 47.1217 26.0215C47.136 26.1075 47.2364 25.9785 47.3654 25.7348C47.9245 24.6738 58.7919 4.91756 58.964 4.63082L59.1647 4.31541L60.1969 4.90322C60.7704 5.23297 61.2722 5.51971 61.3009 5.53405C61.3439 5.57706 54.8493 17.4624 50.7489 24.8602C50.0034 26.1936 49.4299 27.2975 49.4442 27.3118C49.4729 27.3405 52.1683 24.0287 55.4371 19.957C58.7059 15.8853 62.2184 11.5412 63.222 10.2939L65.0571 8.02868L66.0464 8.83154L67.0356 9.63441L62.9353 14.7384C53.3009 26.7097 51.6665 28.7599 51.5088 28.9606C51.2937 29.2473 51.7812 28.8315 61.6019 20.2294C66.2901 16.129 70.1754 12.7599 70.2184 12.7599C70.2614 12.7599 70.6629 13.1756 71.1073 13.6774L71.9245 14.6093L62.7919 22.595C54.0034 30.2652 52.8994 31.2401 53.2149 31.0681C53.3009 31.0251 56.584 29.0466 60.5267 26.6523C72.9424 19.1541 74.5338 18.1935 74.5769 18.2366C74.7776 18.4946 75.8242 20.3871 75.7812 20.4158C75.7525 20.4444 71.05 23.2975 65.3295 26.7384C59.6091 30.1936 54.8349 33.1039 54.7202 33.2186C54.5769 33.3477 54.7202 33.3333 55.1503 33.147C55.5088 33.0036 58.1467 31.957 61.0285 30.8531C63.9102 29.7348 68.8421 27.828 71.9962 26.6093C75.1503 25.3763 77.774 24.4301 77.817 24.4875C77.9747 24.6595 78.7059 26.6667 78.6485 26.724C78.6055 26.7814 57.1718 35.1111 55.8098 35.6129C55.6665 35.6559 55.5661 35.7276 55.5948 35.7563C55.6235 35.7849 61.1002 34.724 67.7668 33.405C75.3367 31.8996 79.9102 31.0538 79.9675 31.1398C80.0966 31.3405 80.4407 33.3907 80.369 33.4767C80.326 33.5054 74.8923 34.595 68.2829 35.8996C61.6593 37.2043 56.2113 38.3226 56.1683 38.3656C56.1253 38.4086 57.3439 38.4229 58.8779 38.3656C60.412 38.3226 65.3152 38.2079 69.774 38.1362C74.2328 38.0645 78.5625 37.9642 79.4227 37.9212L80.9568 37.8495L80.9568 39.1255L80.9568 40.4014L78.7059 40.4875Z\" fill=\"#FFB336\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tMonthly savings\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tSolar energy is free \u2013 use it to power your home to protect yourself from rising costs.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0fc0cf0 elementor-widget__width-initial elementor-widget-tablet__width-initial elementor-widget-mobile__width-inherit block-icons-moving elementor-view-default elementor-position-top elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"0fc0cf0\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon elementor-animation-\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"81\" height=\"77\" viewbox=\"0 0 81 77\" fill=\"none\"><path d=\"M67.3045 66.9942C66.3921 66.1426 62.8743 62.787 59.5085 59.5227C56.1327 56.2685 52.8176 53.0954 52.1384 52.4972L50.9117 51.3922L58.2109 61.388C62.2356 66.8928 65.5303 71.4244 65.5202 71.4751C65.5202 71.5156 65.0843 71.8907 64.5368 72.2759C63.8069 72.8234 63.5231 72.9653 63.4318 72.8335C63.2189 72.5598 56.822 63.8109 52.7264 58.2149C50.638 55.3358 48.8943 53.0041 48.8538 53.0041C48.8234 52.994 51.2564 58.002 54.2572 64.1049C57.2681 70.218 59.7316 75.2362 59.7316 75.2564C59.7518 75.3578 57.5317 76.402 57.4506 76.3209C57.3289 76.1992 46.1977 53.5313 46.1977 53.4096C46.1977 53.3488 46.6742 53.0751 47.252 52.7811C49.4722 51.7166 51.3578 50.0946 52.696 48.1076C55.1797 44.4276 55.8691 40.0684 54.6424 35.8815C51.8545 26.4433 40.551 22.6213 32.5219 28.4201C31.9238 28.856 31.1128 29.5251 30.7174 29.9205C29.7746 30.8633 28.5378 32.7287 27.889 34.1885C25.1213 40.4029 27.2503 47.9657 32.8362 51.7268C33.5053 52.1728 33.9716 52.5581 33.9614 52.6493C33.9412 52.7304 33.5661 53.3285 33.12 53.9773C32.6841 54.616 29.4907 59.3503 26.054 64.4902C22.1104 70.3802 19.7382 73.827 19.6368 73.8067C19.4341 73.7662 17.7107 72.5294 17.7107 72.428C17.7107 72.3672 19.6166 69.4881 27.2097 58.1642C29.4907 54.7681 31.3561 51.9295 31.3561 51.8687C31.3459 51.7977 30.4842 52.6594 29.44 53.7847C28.3857 54.8999 24.9997 58.4481 21.8975 61.6516C18.7954 64.8551 15.8048 67.9877 15.2269 68.6264L14.1929 69.7618L12.3884 67.9573L13.8685 66.3555C14.6896 65.4735 18.0452 61.9557 21.34 58.5596C24.6246 55.1533 27.818 51.818 28.4161 51.1388L29.5211 49.9121L26.6521 52.0106C25.0707 53.1663 20.5695 56.4509 16.6563 59.3098C12.733 62.1788 9.48896 64.5307 9.43827 64.5206C9.38759 64.5307 9.02263 64.0847 8.6374 63.5372C8.08996 62.8073 7.94803 62.5234 8.07982 62.4322C8.56643 62.0673 21.046 52.9332 24.2191 50.6116C26.2568 49.1416 27.9092 47.8947 27.9092 47.8542C27.9194 47.8237 22.9113 50.2568 16.8084 53.2576C10.6953 56.2685 5.67718 58.7319 5.6569 58.7319C5.54539 58.7624 4.52148 56.5219 4.59244 56.4509C4.64313 56.4003 9.62075 53.9368 15.6527 50.9664C21.6745 48.0062 26.6521 45.5427 26.713 45.4819C26.7637 45.4312 21.5731 46.9113 15.1965 48.7666C8.80973 50.6319 3.41646 52.1931 3.21371 52.2337L2.84875 52.3148L2.53448 51.1692C2.36214 50.5305 2.21007 49.9729 2.19994 49.9425C2.19994 49.8817 15.1965 46.0699 23.327 43.7382C24.7969 43.3226 25.9831 42.9475 25.9831 42.9272C25.9831 42.8867 21.7353 43.3226 16.5448 43.8903C11.3543 44.458 5.79883 45.046 4.2072 45.2183L1.30781 45.5225L1.17602 44.2553L1.0341 42.9779L6.09283 42.4406C8.89084 42.1365 14.3247 41.5485 18.177 41.143C22.0496 40.7375 25.3849 40.3624 25.5775 40.332C26.0439 40.2508 26.0844 40.2509 12.3782 39.3385C6.16379 38.9228 1.03409 38.5579 1.00368 38.5274C0.973267 38.497 0.983402 37.9192 1.03409 37.24L1.10507 36.0133L13.2095 36.8243C24.8578 37.6252 26.3176 37.7063 25.9729 37.6049C25.8918 37.5846 20.4174 36.2262 13.8076 34.6041C7.19783 32.9618 1.79443 31.6135 1.80456 31.5831C1.83498 31.2485 2.43311 29.1703 2.4838 29.1804C2.52435 29.1804 7.86693 30.4882 14.3449 32.1001C20.8331 33.7019 26.2669 35.0198 26.4291 35.0198C26.5812 35.0299 26.3075 34.8576 25.7904 34.6447C23.3979 33.6309 4.15652 25.1152 4.03487 25.0138C3.90308 24.9023 4.55189 23.0775 4.83575 22.7734C4.88644 22.7024 9.98572 24.8821 16.1393 27.6091C22.3132 30.3361 27.453 32.5766 27.5544 32.5766C27.6761 32.5766 27.6558 32.536 27.4834 32.4448C27.3415 32.3637 24.584 30.5186 21.34 28.3492C18.0959 26.1797 13.5643 23.1485 11.2631 21.5974C8.58671 19.8132 7.08632 18.7386 7.1066 18.6372C7.14715 18.4345 8.38395 16.711 8.48533 16.711C8.54616 16.711 10.0161 17.6944 22.445 26.0073C26.0135 28.3998 28.9838 30.3564 29.0446 30.3564C29.1156 30.3463 28.2235 29.4744 27.0779 28.3897C25.9324 27.305 22.3639 23.8987 19.1604 20.7965C15.9568 17.6944 12.8446 14.724 12.2566 14.1766L11.1617 13.1831L12.9561 11.3887L14.6187 12.9297C15.5209 13.7711 19.0387 17.1267 22.4044 20.391C25.7803 23.6452 29.0953 26.8184 29.7746 27.4165L31.0012 28.5215L28.9027 25.6525C27.747 24.071 24.4624 19.5699 21.5934 15.6466C18.7346 11.7334 16.3928 8.4792 16.3928 8.43865C16.3826 8.38796 16.8287 8.023 17.366 7.62763C18.2378 6.99909 18.3798 6.93826 18.5318 7.13088C18.6231 7.26267 21.9178 11.7537 25.8411 17.1368C29.7746 22.5098 33.0186 26.9096 33.0592 26.9096C33.0896 26.9197 30.6565 21.9117 27.6558 15.8088C24.6449 9.69573 22.1814 4.67755 22.1814 4.65727C22.1611 4.5559 24.3813 3.51171 24.4624 3.59281C24.5131 3.6435 25.9526 6.54289 27.6659 10.0201C29.3792 13.5177 31.8122 18.4446 33.0592 20.9892C34.3061 23.5337 35.3706 25.6525 35.4314 25.7133C35.4821 25.764 35.2794 24.9327 34.9549 23.8581C33.4546 18.7487 28.7507 2.52835 28.6797 2.21408L28.5986 1.84913L29.7442 1.53485C30.3727 1.35237 30.9303 1.20031 30.9708 1.20031C31.0418 1.19017 31.4169 2.45739 35.3503 16.0419C36.7797 20.9587 37.9659 24.9834 37.9963 24.9936C38.0267 24.9834 37.5908 20.7357 37.023 15.5452C36.4553 10.3547 35.8673 4.7992 35.695 3.20758L35.3909 0.308187L36.6581 0.176401L37.9354 0.0344675L38.4727 5.0932C38.7769 7.89121 39.3547 13.3149 39.7704 17.1774C40.1759 21.05 40.5408 24.3752 40.5814 24.5779C40.6726 25.0544 40.6422 25.5106 41.5546 11.7841C41.9804 5.39733 42.3555 0.115571 42.3758 0.0547449C42.4163 -0.00608145 42.9942 -0.016221 43.6633 0.0243299L44.9001 0.105435L44.089 12.2099C43.6328 18.8704 43.2679 24.507 43.2679 24.73V25.1355L43.3693 24.73C43.4301 24.507 44.7886 19.0326 46.37 12.5647C47.9617 6.08669 49.2998 0.794797 49.3302 0.804935C49.6648 0.835348 51.743 1.43347 51.7329 1.48416C51.7329 1.52471 50.4251 6.8673 48.8132 13.3453C47.2115 19.8335 45.9037 25.2774 45.9037 25.4396C45.9037 25.7032 45.9037 25.7032 45.9949 25.4295C46.1774 24.882 55.788 3.1873 55.9096 3.0251C56.0313 2.88317 58.221 3.73474 58.2312 3.92736C58.221 3.99832 48.9045 25.176 48.357 26.352C48.0833 26.9299 48.428 26.5446 49.1579 25.4498C57.1059 13.5075 62.1443 6.07656 62.2761 6.10697C62.489 6.15766 64.2023 7.36405 64.2023 7.46542C64.2023 7.54653 62.4789 10.1418 54.7033 21.7495C52.4223 25.1456 50.5569 27.9842 50.5569 28.045C50.5671 28.116 51.4693 27.2137 52.5743 26.0276C53.6895 24.8516 57.0451 21.3338 60.0661 18.2114C63.077 15.0991 66.0372 11.997 66.6252 11.3482L67.7302 10.1621L69.5145 11.9463L68.1256 13.4568C67.3754 14.2881 63.8678 17.958 60.3297 21.6177C56.7916 25.2774 53.5678 28.6634 53.1725 29.1399L52.4324 30.0016L55.3419 27.8625C63.7461 21.6887 72.3936 15.3931 72.4747 15.3931C72.5152 15.3931 72.8903 15.8291 73.2756 16.3765C73.823 17.1064 73.9649 17.3903 73.8332 17.4815C73.3465 17.8465 60.867 26.9806 57.6939 29.3021C55.6562 30.7721 54.0037 32.019 54.0037 32.0596C53.9936 32.09 59.0016 29.6569 65.1046 26.6562C71.2176 23.6452 76.2358 21.1818 76.2561 21.1818C76.3575 21.1615 77.4016 23.3817 77.3205 23.4628C77.2698 23.5135 72.2922 25.9769 66.2704 28.9371C60.2385 31.9075 55.2507 34.3811 55.2 34.4318C55.1493 34.5028 55.3115 34.4825 55.5751 34.4014C56.7207 34.0466 78.3749 27.7612 78.6993 27.6801L79.0642 27.599L79.3785 28.7445C79.5508 29.3832 79.7029 29.9408 79.713 29.9712C79.713 30.032 66.7165 33.8438 58.586 36.1755C57.116 36.5911 55.9299 36.9662 55.9299 36.9865C55.9299 37.0271 60.1776 36.5911 65.3681 36.0234C70.5587 35.4557 76.1141 34.8677 77.7058 34.6954L80.6051 34.3912L80.8687 36.9257L74.3603 37.6353C59.0827 39.2878 56.4774 39.5818 56.2239 39.6122C55.8691 39.6629 56.5078 39.7136 69.5348 40.5753C75.7492 40.9909 80.8789 41.3559 80.9093 41.3863C80.9397 41.4167 80.9296 41.9945 80.889 42.6636L80.8079 43.9004L68.7035 43.0894C57.0653 42.2987 55.5954 42.2074 55.9401 42.3088C56.0313 42.3392 59.7518 43.2618 64.2327 44.3566C78.314 47.8339 80.1185 48.2799 80.1185 48.3408C80.078 48.6652 79.4799 50.7434 79.4292 50.7333C79.3886 50.7333 74.046 49.4255 67.568 47.8136C61.0799 46.2118 55.6461 44.8939 55.4839 44.8939C55.2912 44.8838 55.4028 44.975 55.8387 45.1474C56.1935 45.2994 58.7989 46.4247 61.6172 47.6818C64.4456 48.9287 69.2813 51.0678 72.3733 52.4364C75.4755 53.7949 77.9998 54.981 77.9896 55.0519C77.9795 55.2851 77.0772 57.2214 76.9961 57.2214C76.9252 57.2316 55.8792 47.9657 54.5613 47.3574C54.4295 47.2864 54.3079 47.2662 54.3079 47.3067C54.3079 47.3473 58.9307 50.4697 64.5774 54.2511C70.9946 58.5393 74.8266 61.1751 74.8064 61.2765C74.7557 61.5097 73.5493 63.2027 73.4378 63.2128C73.3871 63.2027 68.7744 60.1309 63.1784 56.38C57.5722 52.6189 52.9292 49.5573 52.8683 49.5573C52.8075 49.5573 53.6591 50.4291 54.7844 51.4733C55.8995 52.5276 59.4477 55.9136 62.6512 59.0158C65.8548 62.1179 68.9873 65.1086 69.626 65.6864L70.7614 66.7205L68.9569 68.525L67.3045 66.9942Z\" fill=\"#FFB336\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tIncreased property values\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tInvesting in solar systems can increase the value of your property and make it more attractive to potential buyers.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-6e80b2d animated-fast e-flex e-con-boxed elementor-invisible e-con e-parent\" data-id=\"6e80b2d\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b57fb13 elementor-widget__width-initial elementor-widget-tablet__width-inherit elementor-hidden-desktop img-gray elementor-widget elementor-widget-image\" data-id=\"b57fb13\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"425\" src=\"https:\/\/nau-systems.com\/wp-content\/uploads\/2024\/08\/Rectangle-181-1024x544.png\" class=\"attachment-large size-large wp-image-31\" alt=\"\" srcset=\"https:\/\/nau-systems.com\/wp-content\/uploads\/2024\/08\/Rectangle-181-1024x544.png 1024w, https:\/\/nau-systems.com\/wp-content\/uploads\/2024\/08\/Rectangle-181-300x159.png 300w, https:\/\/nau-systems.com\/wp-content\/uploads\/2024\/08\/Rectangle-181-768x408.png 768w, https:\/\/nau-systems.com\/wp-content\/uploads\/2024\/08\/Rectangle-181-1536x815.png 1536w, https:\/\/nau-systems.com\/wp-content\/uploads\/2024\/08\/Rectangle-181-2048x1087.png 2048w, https:\/\/nau-systems.com\/wp-content\/uploads\/2024\/08\/Rectangle-181-18x10.png 18w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-e79ee72 e-con-full e-flex e-con e-child\" data-id=\"e79ee72\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9c0b29c elementor-widget elementor-widget-heading\" data-id=\"9c0b29c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Take control of your electricity. We are here for you<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fadc1e9 elementor-widget elementor-widget-text-editor\" data-id=\"fadc1e9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Our goal is to help you fully exploit the potential of solar energy, whether through roof mounting, installation on flat roofs or creative solutions such as mounting on fences. We are flexible and adapt to your wishes. Whether you need a complete solar system or just individual modules, we will find the perfect solution for you.<br \/><br \/>We are convinced that renewable energy sources are not only a visionary future, but also an urgent necessity. That is why we place particular emphasis on quality and reliability.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8f0f99d elementor-widget__width-initial elementor-widget-tablet__width-inherit elementor-hidden-tablet elementor-hidden-mobile img-gray elementor-widget elementor-widget-image\" data-id=\"8f0f99d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"425\" src=\"https:\/\/nau-systems.com\/wp-content\/uploads\/2024\/08\/Rectangle-181-1024x544.png\" class=\"attachment-large size-large wp-image-31\" alt=\"\" srcset=\"https:\/\/nau-systems.com\/wp-content\/uploads\/2024\/08\/Rectangle-181-1024x544.png 1024w, https:\/\/nau-systems.com\/wp-content\/uploads\/2024\/08\/Rectangle-181-300x159.png 300w, https:\/\/nau-systems.com\/wp-content\/uploads\/2024\/08\/Rectangle-181-768x408.png 768w, https:\/\/nau-systems.com\/wp-content\/uploads\/2024\/08\/Rectangle-181-1536x815.png 1536w, https:\/\/nau-systems.com\/wp-content\/uploads\/2024\/08\/Rectangle-181-2048x1087.png 2048w, https:\/\/nau-systems.com\/wp-content\/uploads\/2024\/08\/Rectangle-181-18x10.png 18w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-ef1d048 animated-fast e-flex e-con-boxed elementor-invisible e-con e-parent\" data-id=\"ef1d048\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-61f398f e-con-full e-flex e-con e-child\" data-id=\"61f398f\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dea34c9 elementor-widget elementor-widget-heading\" data-id=\"dea34c9\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Shape the future of energy. Become part of our team. <\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b825920 elementor-widget elementor-widget-text-editor\" data-id=\"b825920\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p class=\"my-0\">Our goal is to find qualified specialists who are passionate about actively shaping the energy transition. We are looking for motivated installers (m\/f\/d) to install our photovoltaic systems, from traditional roof installations to creative, custom solutions.<\/p><p class=\"my-0\">We believe that our success is based on the commitment of each individual. Therefore, we offer not only a secure workplace but also an environment where quality, reliability, and team spirit are paramount.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ef572b4 elementor-align-left pop-c elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-button\" data-id=\"ef572b4\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Learn more<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-312c8ca elementor-widget__width-initial elementor-widget-tablet__width-inherit elementor-hidden-tablet elementor-hidden-mobile img-gray elementor-widget elementor-widget-image\" data-id=\"312c8ca\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/nau-systems.com\/wp-content\/uploads\/2025\/07\/img_1965-1024x682.webp\" class=\"attachment-large size-large wp-image-2627\" alt=\"\" srcset=\"https:\/\/nau-systems.com\/wp-content\/uploads\/2025\/07\/img_1965-1024x682.webp 1024w, https:\/\/nau-systems.com\/wp-content\/uploads\/2025\/07\/img_1965-300x200.webp 300w, https:\/\/nau-systems.com\/wp-content\/uploads\/2025\/07\/img_1965-768x511.webp 768w, https:\/\/nau-systems.com\/wp-content\/uploads\/2025\/07\/img_1965-18x12.webp 18w, https:\/\/nau-systems.com\/wp-content\/uploads\/2025\/07\/img_1965.webp 1280w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-335cf10 e-con-full cont-gra e-flex elementor-invisible e-con e-parent\" data-id=\"335cf10\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-7f0f375 e-con-full e-flex e-con e-child\" data-id=\"7f0f375\" data-element_type=\"container\">\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-d55baa0 e-con-full e-flex e-con e-child\" data-id=\"d55baa0\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d95675a elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"d95675a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Start saving on electricity costs today<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-e117b94 animated-fast e-flex e-con-boxed elementor-invisible e-con e-parent\" data-id=\"e117b94\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-f47a0cb e-con-full e-flex e-con e-child\" data-id=\"f47a0cb\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d61cdf8 elementor-widget elementor-widget-heading\" data-id=\"d61cdf8\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">We only use the best equipment in our projects<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b37d4f2 elementor-widget elementor-widget-text-editor\" data-id=\"b37d4f2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>We provide high quality solar energy services based on over 12 years of experience in this industry. <br \/><br \/>NAU SYSTEMS offers customized energy solutions tailored to individual needs. We are committed to providing our customers with reliable and efficient solutions for energy saving and sustainable development.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-6479e80 e-con-full img-gray e-flex e-con e-child\" data-id=\"6479e80\" data-element_type=\"container\">\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-f321984 e-con-full serv-block e-flex e-con e-child\" data-id=\"f321984\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-82c2a4b serv-video elementor-widget elementor-widget-video\" data-id=\"82c2a4b\" data-element_type=\"widget\" data-settings=\"{&quot;video_type&quot;:&quot;hosted&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;play_on_mobile&quot;:&quot;yes&quot;,&quot;mute&quot;:&quot;yes&quot;,&quot;loop&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.23.0 - 05-08-2024 *\/\n.elementor-widget-video .elementor-widget-container{overflow:hidden;transform:translateZ(0)}.elementor-widget-video .elementor-wrapper{aspect-ratio:var(--video-aspect-ratio)}.elementor-widget-video .elementor-wrapper iframe,.elementor-widget-video .elementor-wrapper video{height:100%;width:100%;display:flex;border:none;background-color:#000}@supports not (aspect-ratio:1\/1){.elementor-widget-video .elementor-wrapper{position:relative;overflow:hidden;height:0;padding-bottom:calc(100% \/ var(--video-aspect-ratio))}.elementor-widget-video .elementor-wrapper iframe,.elementor-widget-video .elementor-wrapper video{position:absolute;top:0;right:0;bottom:0;left:0}}.elementor-widget-video .elementor-open-inline .elementor-custom-embed-image-overlay{position:absolute;top:0;right:0;bottom:0;left:0;background-size:cover;background-position:50%}.elementor-widget-video .elementor-custom-embed-image-overlay{cursor:pointer;text-align:center}.elementor-widget-video .elementor-custom-embed-image-overlay:hover .elementor-custom-embed-play i{opacity:1}.elementor-widget-video .elementor-custom-embed-image-overlay img{display:block;width:100%;aspect-ratio:var(--video-aspect-ratio);-o-object-fit:cover;object-fit:cover;-o-object-position:center center;object-position:center center}@supports not (aspect-ratio:1\/1){.elementor-widget-video .elementor-custom-embed-image-overlay{position:relative;overflow:hidden;height:0;padding-bottom:calc(100% \/ var(--video-aspect-ratio))}.elementor-widget-video .elementor-custom-embed-image-overlay img{position:absolute;top:0;right:0;bottom:0;left:0}}.elementor-widget-video .e-hosted-video .elementor-video{-o-object-fit:cover;object-fit:cover}.e-con-inner>.elementor-widget-video,.e-con>.elementor-widget-video{width:var(--container-widget-width);--flex-grow:var(--container-widget-flex-grow)}<\/style>\t\t<div class=\"e-hosted-video elementor-wrapper elementor-open-inline\">\n\t\t\t\t\t<video class=\"elementor-video\" src=\"https:\/\/nau-systems.com\/wp-content\/uploads\/2024\/08\/home-page-block-our-services.mov\" autoplay=\"\" loop=\"\" muted=\"muted\" playsinline=\"\" controlslist=\"nodownload\"><\/video>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-c77659f e-con-full serv-inner e-flex e-con e-child\" data-id=\"c77659f\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a555935 elementor-widget__width-initial serv-inner-text elementor-widget elementor-widget-heading\" data-id=\"a555935\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Complete installation of the system (solar modules and inverters)<\/span>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-88da7dd elementor-align-left pop-c elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-button\" data-id=\"88da7dd\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Learn more<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-a1a4c51 e-con-full serv-block e-flex e-con e-child\" data-id=\"a1a4c51\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-72adc7f serv-video elementor-widget elementor-widget-video\" data-id=\"72adc7f\" data-element_type=\"widget\" data-settings=\"{&quot;video_type&quot;:&quot;hosted&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;play_on_mobile&quot;:&quot;yes&quot;,&quot;mute&quot;:&quot;yes&quot;,&quot;loop&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"e-hosted-video elementor-wrapper elementor-open-inline\">\n\t\t\t\t\t<video class=\"elementor-video\" src=\"https:\/\/nau-systems.com\/wp-content\/uploads\/2026\/05\/nau-systems-eigenmontage.mp4\" autoplay=\"\" loop=\"\" muted=\"muted\" playsinline=\"\" controlslist=\"nodownload\"><\/video>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-628e44b e-con-full serv-inner e-flex e-con e-child\" data-id=\"628e44b\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5b510f4 elementor-widget__width-initial serv-inner-text elementor-widget elementor-widget-heading\" data-id=\"5b510f4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<span class=\"elementor-heading-title elementor-size-default\">NAU SYSTEMS \n- PV Anlage selbst montieren, mit professioneller Montagebegleitung<\/span>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-26859e3 elementor-align-left pop-cal-camp elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-button\" data-id=\"26859e3\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Learn more<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-f3af5d1 e-con-full serv-block e-flex e-con e-child\" data-id=\"f3af5d1\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6106db6 serv-inner-item-l elementor-widget elementor-widget-image\" data-id=\"6106db6\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"889\" src=\"https:\/\/nau-systems.com\/wp-content\/uploads\/2024\/08\/Rectangle-185-921x1024.png\" class=\"attachment-large size-large wp-image-34\" alt=\"\" srcset=\"https:\/\/nau-systems.com\/wp-content\/uploads\/2024\/08\/Rectangle-185-921x1024.png 921w, https:\/\/nau-systems.com\/wp-content\/uploads\/2024\/08\/Rectangle-185-270x300.png 270w, https:\/\/nau-systems.com\/wp-content\/uploads\/2024\/08\/Rectangle-185-768x854.png 768w, https:\/\/nau-systems.com\/wp-content\/uploads\/2024\/08\/Rectangle-185-1382x1536.png 1382w, https:\/\/nau-systems.com\/wp-content\/uploads\/2024\/08\/Rectangle-185-1843x2048.png 1843w, https:\/\/nau-systems.com\/wp-content\/uploads\/2024\/08\/Rectangle-185-11x12.png 11w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-8e7eda3 e-con-full serv-inner e-flex e-con e-child\" data-id=\"8e7eda3\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-108939f elementor-widget__width-initial serv-inner-text elementor-widget elementor-widget-heading\" data-id=\"108939f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Energy saving advice<\/span>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-72caffd elementor-align-left pop-c elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-button\" data-id=\"72caffd\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Learn more<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-60b4f20 e-con-full serv-block e-flex e-con e-child\" data-id=\"60b4f20\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-277e326 serv-inner-item-l elementor-widget elementor-widget-image\" data-id=\"277e326\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"889\" src=\"https:\/\/nau-systems.com\/wp-content\/uploads\/2024\/08\/Rectangle-184-921x1024.png\" class=\"attachment-large size-large wp-image-33\" alt=\"\" srcset=\"https:\/\/nau-systems.com\/wp-content\/uploads\/2024\/08\/Rectangle-184-921x1024.png 921w, https:\/\/nau-systems.com\/wp-content\/uploads\/2024\/08\/Rectangle-184-270x300.png 270w, https:\/\/nau-systems.com\/wp-content\/uploads\/2024\/08\/Rectangle-184-768x854.png 768w, https:\/\/nau-systems.com\/wp-content\/uploads\/2024\/08\/Rectangle-184-1382x1536.png 1382w, https:\/\/nau-systems.com\/wp-content\/uploads\/2024\/08\/Rectangle-184-1843x2048.png 1843w, https:\/\/nau-systems.com\/wp-content\/uploads\/2024\/08\/Rectangle-184-11x12.png 11w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-0f0df69 e-con-full serv-inner e-flex e-con e-child\" data-id=\"0f0df69\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d4283df elementor-widget__width-initial serv-inner-text elementor-widget elementor-widget-heading\" data-id=\"d4283df\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Maintenance, repair, servicing<\/span>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aa23eae elementor-align-left pop-c elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-button\" data-id=\"aa23eae\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Learn more<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-f8c3f90 e-con-full serv-block e-flex e-con e-child\" data-id=\"f8c3f90\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2e9ef0f serv-inner-item elementor-widget elementor-widget-image\" data-id=\"2e9ef0f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"422\" src=\"https:\/\/nau-systems.com\/wp-content\/uploads\/2024\/09\/image-12-1024x540.png\" class=\"attachment-large size-large wp-image-1639\" alt=\"\" srcset=\"https:\/\/nau-systems.com\/wp-content\/uploads\/2024\/09\/image-12-1024x540.png 1024w, https:\/\/nau-systems.com\/wp-content\/uploads\/2024\/09\/image-12-300x158.png 300w, https:\/\/nau-systems.com\/wp-content\/uploads\/2024\/09\/image-12-768x405.png 768w, https:\/\/nau-systems.com\/wp-content\/uploads\/2024\/09\/image-12-1536x810.png 1536w, https:\/\/nau-systems.com\/wp-content\/uploads\/2024\/09\/image-12-18x9.png 18w, https:\/\/nau-systems.com\/wp-content\/uploads\/2024\/09\/image-12.png 1947w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-0e0ed3b e-con-full serv-inner e-flex e-con e-child\" data-id=\"0e0ed3b\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b4f5fb8 elementor-align-left pop-cal-camp elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-button\" data-id=\"b4f5fb8\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Learn more<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Tailor-made solutions for your energy needs Enjoy more independence and fun with environmentally friendly energy. NAU SYSTEMS offers you everything you need for portable batteries, camping equipment and EcoFlow photovoltaic systems for your home storage - for more savings and freedom. Get free advice Sustainable energy Supply your home with emission-free, renewable energy directly from the [...]<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"footnotes":""},"class_list":["post-60","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/nau-systems.com\/en\/wp-json\/wp\/v2\/pages\/60"}],"collection":[{"href":"https:\/\/nau-systems.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/nau-systems.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/nau-systems.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nau-systems.com\/en\/wp-json\/wp\/v2\/comments?post=60"}],"version-history":[{"count":76,"href":"https:\/\/nau-systems.com\/en\/wp-json\/wp\/v2\/pages\/60\/revisions"}],"predecessor-version":[{"id":2793,"href":"https:\/\/nau-systems.com\/en\/wp-json\/wp\/v2\/pages\/60\/revisions\/2793"}],"wp:attachment":[{"href":"https:\/\/nau-systems.com\/en\/wp-json\/wp\/v2\/media?parent=60"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}